{"id":4067,"date":"2023-12-20T14:08:19","date_gmt":"2023-12-20T14:08:19","guid":{"rendered":"https:\/\/www.eha-consulting.com\/?p=4067"},"modified":"2024-07-18T18:07:52","modified_gmt":"2024-07-18T18:07:52","slug":"interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues","status":"publish","type":"post","link":"https:\/\/www.eha-consulting.com\/en\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/","title":{"rendered":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues"},"content":{"rendered":"\n<p>La cybers\u00e9curit\u00e9 est un enjeu majeur pour les entreprises de toutes tailles : les attaques se multiplient et les attaquants sont de plus en plus performants.<\/p>\n\n\n\n<p>Lors de la cyber attaque de janvier 2020, le cabinet EH&amp;A avait accompagn\u00e9 la direction g\u00e9n\u00e9rale de Bouygues Construction pour comprendre les enjeux de cette crise et s\u2019y pr\u00e9parer.<\/p>\n\n\n\n<p>Nous n\u2019\u00e9tions pas dans le c\u0153ur du r\u00e9acteur op\u00e9rationnel IT, notre mission \u00e9tait strat\u00e9gique mais \u00e0 la lumi\u00e8re de la multiplication des cyber-attaques et leurs difficult\u00e9s croissantes, nous avons souhait\u00e9 recueillir et partager la vision du responsable de la s\u00e9curit\u00e9 des syst\u00e8mes d\u2019information (RSSI) de l\u2019\u00e9poque, Thomas DEGARDIN, qui a gentiment accept\u00e9 de nous r\u00e9pondre.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg\" alt=\"\" class=\"wp-image-4074\" width=\"343\" height=\"459\" srcset=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg 338w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d-224x300.jpg 224w\" sizes=\"auto, (max-width: 343px) 100vw, 343px\" \/><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\" type=\"1\"><li><strong>Aujourd\u2019hui vous \u00eates Coordinateur Cybers\u00e9curit\u00e9 du groupe Bouygues, quelles sont vos missions lors d\u2019une crise cyber ?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>J\u2019ai trois grandes missions sur cette activit\u00e9, avec une premi\u00e8re mission de synergie entre les six m\u00e9tiers du groupe Bouygues, qui sont tr\u00e8s diff\u00e9rents. Mon but est d\u2019animer les diff\u00e9rentes instances au sein de cette communaut\u00e9 cyber, trouver des chantiers communs ou encore aider mes coll\u00e8gues RSSI \u00e0 prendre du recul. J\u2019ai occup\u00e9 cette fonction <\/em><em>[<\/em><em>RSSI n.d.l.r.<\/em><em>]<\/em><em> pendant 5 ans au sein de Bouygues Construction et je peux, gr\u00e2ce \u00e0 cela, les aider \u00e0 voir ce qu\u2019il se passe ailleurs. Ma deuxi\u00e8me mission est d\u2019animer la communaut\u00e9 \u201cBYTECH Cyber\u201d, qui rassemble environ 300 collaborateurs de Bouygues travaillant sur des sujets de cybers\u00e9curit\u00e9 en coordonnant les temps forts de cette communaut\u00e9. Enfin, la troisi\u00e8me mission est de repr\u00e9senter le Groupe dans les diff\u00e9rentes instances ou assembl\u00e9es parlant de cybers\u00e9curit\u00e9, que ce soit c\u00f4t\u00e9 assurances, ou dans diff\u00e9rentes communaut\u00e9s d\u2019int\u00e9r\u00eats autour de ces sujets.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Vous parlez de synergie entre les diff\u00e9rents m\u00e9tiers du Groupe, comment faites-vous pour cr\u00e9er des ponts entre les diff\u00e9rentes fonctions&nbsp;?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Il existe depuis longtemps un comit\u00e9 s\u00e9curit\u00e9 informatique Groupe qui r\u00e9unit tous les RSSI tous les mois. C\u2019est un lieu qui nous permet d\u2019\u00e9changer et d\u2019identifier des chantiers transverses. Chaque RSSI est investi et tr\u00e8s comp\u00e9tent dans son m\u00e9tier, il avance sur sa feuille de route et ses risques sont tr\u00e8s diff\u00e9rents de ceux des autres. J\u2019agis comme entremetteur entre les diff\u00e9rents m\u00e9tiers. Si un m\u00e9tier travaille sur un sujet et qu\u2019un autre se pose des questions dessus, je les mets en relation. Si le sujet int\u00e9resse plusieurs RSSI, une d\u00e9marche Groupe peut \u00eatre mise en place.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>En cas de crise cyber, quelles sont vos missions ?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Fort heureusement, depuis ma prise de fonction en d\u00e9but d\u2019ann\u00e9e, nous n\u2019avons pas connu de crise majeure au sein du Groupe donc \u00e7a ne s\u2019est pas r\u00e9v\u00e9l\u00e9 <\/em><em>[<\/em><em>rire n.d.l.r.<\/em><em>]!<\/em><em> Mais pour faire le parall\u00e8le avec ce que j\u2019ai v\u00e9cu en janvier 2020, quand vous \u00eates RSSI d\u2019un M\u00e9tier, quand vous \u00eates au pilotage d\u2019une crise \u00e0 r\u00e9fl\u00e9chir \u00e0 comment contenir la cyberattaque, comment reconstruire ou red\u00e9marrer sans prendre trop de risques, vous \u00eates d\u00e9j\u00e0 tellement absorb\u00e9 par ces sujets qu\u2019il est compliqu\u00e9 de sortir de l\u2019activit\u00e9 urgente pour aller communiquer et \u00e9changer avec le reste du Groupe ou avec l\u2019ext\u00e9rieur. C\u2019est l\u00e0 o\u00f9 j\u2019interviens en tant que coordinateur. Je suis un peu un aide de camp pour le RSSI en cas de crise. Je r\u00e9cup\u00e8re les informations pour les diffuser au sein du Groupe, notamment en partageant les indicateurs, en faisant des points de situation (\u00e9tat des lieux). L\u2019objectif est de donner de l\u2019air au RSSI et lui permettre de se concentrer sur la gestion de la crise.&nbsp;Je suis un soutien, au service du RSSI M\u00e9tier en temps de crise : mon r\u00f4le n\u2019est pas de diriger la cellule de crise mais de le soutenir et l\u2019assister.\u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>&nbsp;En janvier 2020, lorsque vous \u00e9tiez chez Bouygues Construction, l\u2019entreprise a \u00e9t\u00e9 la cible d\u2019une cyberattaque majeure. Pouvez-vous nous en parler&nbsp;?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Bouygues Construction a \u00e9t\u00e9 touch\u00e9 par une cyberattaque de type \u201ccryptolocker\u201d dans la nuit du 29 au 30 janvier 2020. A l\u2019\u00e9poque, Bouygues Construction, c\u2019\u00e9tait un peu plus de 60 000 collaborateurs, 30 000 postes de travail et 3000 serveurs. La premi\u00e8re d\u00e9cision a \u00e9t\u00e9 de couper l\u2019alimentation \u00e9lectrique du syst\u00e8me d\u2019information, pour enrayer la propagation du virus. Imaginez un r\u00e9seau monde, plusieurs centaines d\u2019applications majeures: tout cela \u00e0 l\u2019arr\u00eat. Les \u00e9quipes qui travaillaient sur ces syst\u00e8mes ne pouvaient plus rien faire, ne pouvaient plus se connecter aux unit\u00e9s finances, traiter les fiches de salaires. On bascule alors en mode crise. On est fin du mois et il y a une priorit\u00e9 donn\u00e9e par le COMEX : payer les salaires des collaborateurs.<\/em><\/p>\n\n\n\n<p><em>Une cellule de crise op\u00e9rationnelle c\u00f4t\u00e9 DSI se monte, avec une codirection, pour tenir 24\/7 car au d\u00e9but de la crise, c\u2019est du non-stop. Se cr\u00e9e \u00e9galement une cellule d\u00e9cisionnelle au niveau comit\u00e9 de management de Bouygues Construction avec des interactions fr\u00e9quentes entre les deux. Le r\u00f4le de la cellule d\u00e9cisionnelle \u00e9tait de donner les priorit\u00e9s de red\u00e9marrage pour que l\u2019entreprise surmonte cette difficult\u00e9 et elle laissait la cellule op\u00e9rationnelle s\u2019occuper des probl\u00e9matiques techniques. &nbsp;<\/em><\/p>\n\n\n\n<p><em>Au niveau \u00e9quipe, la DSI avait \u00e9t\u00e9 form\u00e9e \u00e0 la m\u00e9thodologie AGILE, on s\u2019est donc organis\u00e9 en \u201cstreams\u201d, avec des streams leaders qui n\u2019\u00e9taient pas forc\u00e9ment des experts techniques mais qui avaient les sachants autour d\u2019eux. La grande difficult\u00e9 est l\u2019ampleur de cette crise. Quand on commence, on ne sait pas trop ce qui nous tombe dessus. Au d\u00e9but, on est dans le flou, la premi\u00e8re difficult\u00e9 est de savoir ce qu\u2019il se passe. Les autres difficult\u00e9s apparaissent au fur et \u00e0 mesure.<\/em><\/p>\n\n\n\n<p><em>Il y a eu, de plus, une concomitance des crises. 6-7 semaines apr\u00e8s le d\u00e9marrage de cette crise informatique, la pand\u00e9mie du COVID-19 a d\u00e9but\u00e9. Il a fallu travailler \u00e0 la r\u00e9solution de la crise tout en \u00e9tant confin\u00e9s. Cela a ajout\u00e9 des cellules de crise dans la crise.\u00a0\u00bb<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"746\" src=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-1024x746.png\" alt=\"\" class=\"wp-image-4076\" srcset=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-1024x746.png 1024w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-300x219.png 300w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-768x560.png 768w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td.png 1106w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Face \u00e0 ce type de crise, quelle est selon vous la strat\u00e9gie \u00e0 adopter\u00a0?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Je ne vais pas vous donner une strat\u00e9gie magique parce qu\u2019il n\u2019y en a pas. \u00c7a serait trop simple, on l\u2019aurait tous et on serait tous sauv\u00e9s.<\/em><\/p>\n\n\n\n<p><em>Le point qui me semble primordial c\u2019est d\u2019enclencher des investigations, du forensic. Si la situation devait se repr\u00e9senter, nous referions sans h\u00e9siter ces analyses.<\/em><\/p>\n\n\n\n<p><em>Si on ne sait pas ce qu\u2019il s\u2019est pass\u00e9, c\u2019est extr\u00eamement compliqu\u00e9 voire impossible de red\u00e9marrer en toute confiance. Ne pas conduire ces investigations, c\u2019est comme jouer \u00e0 la roulette russe, prendre des d\u00e9cisions et croiser les doigts. \u00c7a ne fonctionne pas. Il faut se faire aider.<\/em><\/p>\n\n\n\n<p><em>Mais vous savez, je pense que l\u2019on peut se pr\u00e9parer \u00e0 tous les plans, ce sera toujours le plan+1 qui fonctionnera. Certains experts auront un avis, d\u2019autres diront l\u2019inverse. Chaque attaque est diff\u00e9rente mais il faut savoir ce qu\u2019il se passe pr\u00e9cis\u00e9ment pour pouvoir agir en cons\u00e9quence. A mesure que la crise se poursuit, l\u2019enqu\u00eate am\u00e8ne de nouveaux \u00e9l\u00e9ments qui permettent d\u2019ajuster les actions, on s\u2019adapte au fur et \u00e0 mesure.&nbsp;La strat\u00e9gie repose donc sur l\u2019enqu\u00eate. L\u2019\u00e9change d\u2019informations entre les cellules est la cl\u00e9.<\/em><\/p>\n\n\n\n<p><em>En ce qui concerne la communication de crise, si l\u2019entreprise ne communique pas, les hackers le feront. Ils ont des services de communication eux aussi. Si vous ne parlez pas en premier, il faudra traiter la parole de la partie adverse. Cela prend plus de temps de d\u00e9montrer qu\u2019un hacker communique des informations incorrectes que d\u2019annoncer en premier, ce que vous savez, ou ce que vous ne savez pas. Vous avez le droit de dire \u00ab&nbsp;pour l\u2019instant on ne sait pas&nbsp;\u00bb. \u00bb<\/em><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-2.png\" alt=\"\" class=\"wp-image-4078\" width=\"351\" height=\"312\" srcset=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-2.png 702w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-2-300x266.png 300w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-1.png\" alt=\"\" class=\"wp-image-4080\" width=\"352\" height=\"331\" srcset=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-1.png 660w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/itw-td-1-300x282.png 300w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Quels enseignements le Groupe a-t-il tir\u00e9 de cette crise&nbsp;? Cela a-t-il chang\u00e9 votre organisation&nbsp;? Cela a-t-il chang\u00e9 la culture de la crise, en particulier cyber&nbsp;? Avez-vous pris des mesures particuli\u00e8res pour \u00e9viter que ce type d\u2019incident ne se reproduise&nbsp;?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab\u00a0<em>Tout \u00e0 fait. Les trois mots souvent martel\u00e9s par le DSI \u00e9taient\u00a0: plus jamais \u00e7a. Plus jamais une crise avec une telle ampleur. Il est important de se reconstruire, de r\u00e9organiser. Cela a \u00e9t\u00e9 une vraie prise de conscience et pas seulement du Groupe mais de moi aussi. La crise est une dose d\u2019humilit\u00e9 XXL. Depuis cette crise, <a>le sujet cyber a \u00e9t\u00e9 saisi par la direction g\u00e9n\u00e9rale de fa\u00e7on encore plus pr\u00e9cise<\/a>, avec des suivis r\u00e9guliers dans tous les M\u00e9tiers du Groupe. \u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong> Vous \u00eates dans le milieu de la cybers\u00e9curit\u00e9 depuis 20 ans, quelles sont les \u00e9volutions que vous avez pu constater\u00a0? Quels sont les risques et les enjeux \u00e9mergents ?<\/strong><\/li><\/ul>\n\n\n\n<p><em>\u00ab&nbsp;Effectivement, il y a dans un premier temps l\u2019\u00e9volution technologique. Il y a 20 ans j\u2019avais un firewall et un antivirus. Le monde technique a bien \u00e9volu\u00e9 mais c\u2019est finalement le rapport avec la menace qui a chang\u00e9. C\u2019est une course gendarme-voleur. Ce qui a chang\u00e9, ce sont les attaquants, qui \u00e9taient peut-\u00eatre \u00e0 une \u00e9poque, des adolescents en sweat \u00e0 capuche dans un garage et qui sont maintenant de vraies organisations cybercriminelles tr\u00e8s bien organis\u00e9es avec des processus de recrutement, qui vont chercher les meilleurs, qui sont parfois sp\u00e9cialis\u00e9es. Nous n\u2019avons plus trois personnes en face de nous qui tentent de nous attaquer mais de vraies structures. Ils investissent du temps et de l\u2019argent sur leurs attaques et doivent maximiser les r\u00e9sultats. Il faut vraiment prendre en compte cette \u00e9volution de la menace. De plus, l\u2019approche traditionnelle qui consiste \u00e0 se prot\u00e9ger tout seul ne suffit plus, il faut prendre en compte les fournisseurs et \u00eatre dans une coop\u00e9ration \u00e9tendue de toute la cha\u00eene de production.\u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong> Le recours \u00e0 l\u2019intelligence artificielle (IA) dans l\u2019aide \u00e0 la prise de d\u00e9cision est de plus en plus \u00e9tudi\u00e9e dans le domaine de la gestion de crise. Quel est votre avis sur la question\u00a0?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Il faut s\u2019y pr\u00e9parer car \u00e7a arrivera. Il ne faut pas la mettre de c\u00f4t\u00e9 en se disant que c\u2019est dangereux, les attaquants s\u2019en serviront. Sur des cas plus sensibles, il y a toujours besoin de l\u2019intelligence humaine mais l\u2019IA viendra s\u00fbrement aider. Je ne peux pas encore vous dire ce qu\u2019elle va nous apporter mais je pense qu\u2019il est important d\u2019\u00e9tablir des limites sur ce que les collaborateurs peuvent faire ou ne pas faire avec. Comment embrasser cette r\u00e9volution est notre questionnement actuel. Demain, elle viendra tr\u00e8s certainement aider la prise de d\u00e9cision, il faudra l\u2019\u00e9valuer \u00e0 ce moment-l\u00e0. Il ne faut pas l\u2019interdire, il faut d\u00e9finir les r\u00e8gles du jeu. C\u2019est un changement dans notre fa\u00e7on de faire, il faut accompagner ce changement qui est presque soci\u00e9tal.&nbsp;\u00bb<\/em><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong> Si vous aviez des conseils \u00e0 donner, quels seraient-ils\u00a0?<\/strong><\/li><\/ul>\n\n\n\n<p>\u00ab&nbsp;<em>Pour conclure, si l\u2019on venait me demander comment g\u00e9rer une crise, je dirais \u00ab&nbsp;ne reste pas tout seul&nbsp;\u00bb. Il faut s\u2019entourer, aller chercher des renforts, de l\u2019aide, des bonnes pratiques. Il ne faut pas h\u00e9siter : des gens sont pr\u00eats \u00e0 aider, ils sont bienveillants. Il faut prendre soin des collaborateurs qui m\u00e8nent un vrai combat. Il ne faut pas sous-estimer l\u2019impact qu\u2019une crise peut avoir sur le psychologique, \u00e7a laisse des marques. Il ne faut pas le n\u00e9gliger.<\/em><\/p>\n\n\n\n<p><em>Nous avons \u00e9t\u00e9 aid\u00e9s, \u00e0 tous niveaux. C\u2019est int\u00e9ressant d\u2019avoir des gens qui ont l\u2019expertise de la gestion de crise avec de bonnes pratiques vues ailleurs qui peuvent \u00eatre transpos\u00e9es. La gestion de crise est un syst\u00e8me qui n\u2019existe pas, qu\u2019il faut cr\u00e9er. Il faut donc \u00eatre accompagn\u00e9 pendant, mais aussi en amont, pour se pr\u00e9parer, s\u2019entra\u00eener, se tester, pour avoir les premiers reflexes. C\u2019est comme la marche, le plus dur est de faire le premier pas, apr\u00e8s \u00e7a fonctionne, mais si on ne le fait pas, on tombe et on se fait mal.&nbsp;\u00bb<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cybers\u00e9curit\u00e9 est un enjeu majeur pour les entreprises de toutes tailles : les attaques se multiplient et les attaquants sont de plus en plus performants. Lors de la cyber attaque de janvier 2020, le cabinet EH&amp;A avait accompagn\u00e9 la direction g\u00e9n\u00e9rale de Bouygues Construction pour comprendre les enjeux de cette crise et s\u2019y pr\u00e9parer. [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4067","post","type-post","status-publish","format-standard","hentry","category-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA\" \/>\n<meta property=\"og:description\" content=\"La cybers\u00e9curit\u00e9 est un enjeu majeur pour les entreprises de toutes tailles : les attaques se multiplient et les attaquants sont de plus en plus performants. Lors de la cyber attaque de janvier 2020, le cabinet EH&amp;A avait accompagn\u00e9 la direction g\u00e9n\u00e9rale de Bouygues Construction pour comprendre les enjeux de cette crise et s\u2019y pr\u00e9parer. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/\" \/>\n<meta property=\"og:site_name\" content=\"E&amp;HA\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-20T14:08:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-18T18:07:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg\" \/>\n<meta name=\"author\" content=\"murielle\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"murielle\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/\"},\"author\":{\"name\":\"murielle\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/4354fd2ad23ba1e618a5b3c9f36d2998\"},\"headline\":\"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues\",\"datePublished\":\"2023-12-20T14:08:19+00:00\",\"dateModified\":\"2024-07-18T18:07:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/\"},\"wordCount\":2145,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/thomas-d.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/\",\"name\":\"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/thomas-d.jpg\",\"datePublished\":\"2023-12-20T14:08:19+00:00\",\"dateModified\":\"2024-07-18T18:07:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/4354fd2ad23ba1e618a5b3c9f36d2998\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/thomas-d.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/thomas-d.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/\",\"name\":\"E&amp;HA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eha-consulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/4354fd2ad23ba1e618a5b3c9f36d2998\",\"name\":\"murielle\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g\",\"caption\":\"murielle\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/","og_locale":"en_US","og_type":"article","og_title":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA","og_description":"La cybers\u00e9curit\u00e9 est un enjeu majeur pour les entreprises de toutes tailles : les attaques se multiplient et les attaquants sont de plus en plus performants. Lors de la cyber attaque de janvier 2020, le cabinet EH&amp;A avait accompagn\u00e9 la direction g\u00e9n\u00e9rale de Bouygues Construction pour comprendre les enjeux de cette crise et s\u2019y pr\u00e9parer. [&hellip;]","og_url":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/","og_site_name":"E&amp;HA","article_published_time":"2023-12-20T14:08:19+00:00","article_modified_time":"2024-07-18T18:07:52+00:00","og_image":[{"url":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg","type":"","width":"","height":""}],"author":"murielle","twitter_card":"summary_large_image","twitter_misc":{"Written by":"murielle","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#article","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/"},"author":{"name":"murielle","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/4354fd2ad23ba1e618a5b3c9f36d2998"},"headline":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues","datePublished":"2023-12-20T14:08:19+00:00","dateModified":"2024-07-18T18:07:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/"},"wordCount":2145,"commentCount":0,"image":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg","articleSection":["Articles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/","url":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/","name":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues - E&amp;HA","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#primaryimage"},"image":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg","datePublished":"2023-12-20T14:08:19+00:00","dateModified":"2024-07-18T18:07:52+00:00","author":{"@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/4354fd2ad23ba1e618a5b3c9f36d2998"},"breadcrumb":{"@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#primaryimage","url":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg","contentUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2023\/12\/thomas-d.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eha-consulting.com\/interview-de-thomas-degardin-coordinateur-cybersecurite-du-groupe-bouygues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eha-consulting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Interview de Thomas Degardin, coordinateur cybers\u00e9curit\u00e9 du groupe Bouygues"}]},{"@type":"WebSite","@id":"https:\/\/www.eha-consulting.com\/#website","url":"https:\/\/www.eha-consulting.com\/","name":"E&amp;HA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eha-consulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/4354fd2ad23ba1e618a5b3c9f36d2998","name":"murielle","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b073cb5f25b04177020a18599df841593f196f10c1205b40621b1b6df7547676?s=96&d=mm&r=g","caption":"murielle"}}]}},"_links":{"self":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/4067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=4067"}],"version-history":[{"count":3,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/4067\/revisions"}],"predecessor-version":[{"id":4098,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/4067\/revisions\/4098"}],"wp:attachment":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=4067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=4067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=4067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}