{"id":3300,"date":"2022-09-30T12:40:44","date_gmt":"2022-09-30T12:40:44","guid":{"rendered":"https:\/\/www.eha-consulting.com\/conflit-autour-de-lusage-de-leau\/"},"modified":"2024-09-18T09:35:37","modified_gmt":"2024-09-18T09:35:37","slug":"conflit-autour-de-lusage-de-leau","status":"publish","type":"post","link":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/","title":{"rendered":"Conflit autour de l&#8217;usage de l&#8217;eau"},"content":{"rendered":"\n<p><strong>L\u2019expansion fr\u00e9n\u00e9tique des data centers et la r\u00e9alit\u00e9 frappante du r\u00e9chauffement climatique obligent les industriels \u00e0 repenser leur strat\u00e9gie de refroidissement.<\/strong><\/p>\n\n\n\n<p>Les data centers concentrent aujourd\u2019hui 1% de la consommation globale d\u2019\u00e9lectricit\u00e9 et pourraient repr\u00e9senter 3% de cette consommation en 2030. Ils sont \u00e9galement responsables de 0,3% des \u00e9missions de dioxyde de carbone.<\/p>\n\n\n\n<p>L\u2019\u00e9lectricit\u00e9 utilis\u00e9e sert \u00e0 faire tourner les infrastructures, mais surtout \u00e0 refroidir les serveurs via la climatisation. Pour limiter leur consommation \u00e9nerg\u00e9tique, les data centers se tournent de plus en plus vers le <em>water cooling<\/em>. Ce proc\u00e9d\u00e9 de refroidissement favorise ainsi l\u2019eau froide \u00e0 la climatisation. Il entretient cependant une d\u00e9pendance suppl\u00e9mentaire \u00e0 cette ressource, qui se rarifie du fait des hausses des temp\u00e9ratures et de son utilisation excessive dans les diff\u00e9rentes industries. Sa raret\u00e9 devient forc\u00e9ment un facteur de crise.&nbsp;<\/p>\n\n\n\n<p><em>Le saviez-vous<\/em> s\u2019int\u00e9resse ici aux \u00e9volutions techniques en cours de d\u00e9veloppement ou d\u00e9j\u00e0 mises en \u0153uvre pour r\u00e9duire la consommation d\u2019eau dans les data centers. En effet, avec les nombreux \u00e9pisodes de canicule et de s\u00e9cheresse qu\u2019ont subie la France et l\u2019Europe durant l\u2019\u00e9t\u00e9, la question des restrictions d\u2019eau risque de s\u2019imposer pour plusieurs secteurs industriels. La priorit\u00e9 \u00e9tant donn\u00e9 \u00e0 la consommation des particuliers et de l\u2019agriculture, les entreprises industrielles seront les premi\u00e8res p\u00e9nalis\u00e9es.&nbsp;<\/p>\n\n\n\n<p>La consommation en eau est ainsi r\u00e9partie en France&nbsp;: 45% pour l\u2019agriculture, 31% pour le refroidissement des centrales \u00e9lectriques, 21% pour l\u2019eau potable et 4% pour l\u2019usage industriel.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pour faire face \u00e0 ce d\u00e9fi, les op\u00e9rateurs de centre de donn\u00e9es europ\u00e9ens se sont r\u00e9unis pour mettre au point le <em>Climate Neutral Data Centre Pact<\/em> (CNDCP), s\u2019engageant ainsi \u00e0 porter davantage d&#8217;attention \u00e0 l&#8217;usage de l&#8217;eau au sein de leurs installations.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Dans ce contexte crisog\u00e8ne, les op\u00e9rateurs des data centers doivent prendre en compte diff\u00e9rents \u00e9l\u00e9ments&nbsp;: la g\u00e9ographie, la technologie et l\u2019ann\u00e9e de construction des data centers. Ces conditions sont essentielles dans la gestion des risques et la planification, lors de la conception et de la maintenance de ces installations.<\/p>\n\n\n\n<p><strong>I &#8211; La g\u00e9ographie&nbsp;:<\/strong><\/p>\n\n\n\n<p>Le choix du lieu d\u2019installation d\u2019un centre de donn\u00e9es influence fortement la technologie de <em>water cooling<\/em> utilis\u00e9e. Lorsque le data center se situe \u00e0 proximit\u00e9 d\u2019un point d\u2019eau (mer, r\u00e9serve aquif\u00e8re\u2026), le refroidissement est op\u00e9r\u00e9 par pompage. Eolas, \u00e0 Grenoble, utilise la nappe phr\u00e9atique pour refroidir ses centres et a fait \u00e9voluer son indice d\u2019efficacit\u00e9 \u00e9nerg\u00e9tique \u00e0 1,2. Interxion d\u00e9ploie du <em>river cooling<\/em> depuis 2010 et s\u2019est m\u00eame lanc\u00e9 en 2016 dans le <em>river cooling<\/em> \u00e0 l\u2019eau ti\u00e8de \u00e0 Marseille, en puisant l\u2019eau d\u2019une ancienne galerie mini\u00e8re. Cela a permis de r\u00e9duire le <em>Power usage effectiveness<\/em> \u00e0 1,2 alors que la plupart des data centers ont un taux de 1,7.<\/p>\n\n\n\n<p>A l\u2019inverse, les centres, ne pouvant pas b\u00e9n\u00e9ficier d\u2019un apport hydrique externe, fonctionnent \u00e0 l\u2019aide d\u2019un circuit d\u2019eau ferm\u00e9. Ce proc\u00e9d\u00e9 repr\u00e9sente toutefois une menace pour l\u2019environnement&nbsp;: certains op\u00e9rateurs d\u00e9cident de purifier l\u2019eau avec des produits chimiques extr\u00eamement toxiques qui impactent les \u00e9cosyst\u00e8mes quand ils sont d\u00e9vers\u00e9s dans les rivi\u00e8res apr\u00e8s usage.<\/p>\n\n\n\n<p>En parall\u00e8le de ces catastrophes \u00e9cologiques, certaines technologies de refroidissement peuvent avoir des cons\u00e9quences sur la sant\u00e9 des habitants aux alentours. Par exemple, en Am\u00e9rique du Nord, le refroidissement se fait principalement par voie humide (ces grandes fum\u00e9es que l\u2019on voit sortir des chemin\u00e9es des usines). En plus d\u2019une consommation tr\u00e8s \u00e9lev\u00e9e en eau, cette pratique engendre des \u00e9pid\u00e9mies de l\u00e9gionellose, une infection pulmonaire. En 2012, \u00e0 \u00c9dimbourg, les cas de l\u00e9gionelloses, li\u00e9s \u00e0 cette m\u00e9thode de <em>water cooling,<\/em> ont provoqu\u00e9 le d\u00e9c\u00e8s de 92 personnes. Par cons\u00e9quent, plusieurs data centers strat\u00e9giques pour les \u00e9tablissements de services financiers \u00e9cossais ont \u00e9t\u00e9 ferm\u00e9s.<\/p>\n\n\n\n<p>Les temp\u00e9ratures in\u00e9gal\u00e9es de cet \u00e9t\u00e9 au Royaume-Uni ont provoqu\u00e9 plusieurs pannes techniques au sein des infrastructures de refroidissement, montrant \u00e0 nouveau l\u2019impact du r\u00e9chauffement climatique. Ce ph\u00e9nom\u00e8ne a engendr\u00e9 des taux d\u2019erreur \u00e9lev\u00e9s, des latences ou des services indisponibles pour certains clients de Google et d\u2019Oracle, les principales entreprises de donn\u00e9es. Ces deux entit\u00e9s ont m\u00eame d\u00e9cid\u00e9 de mettre hors tension des serveurs pour \u00e9viter tout dommage \u00e0 long terme pour leurs clients. Cette action a entra\u00een\u00e9 l\u2019indisponibilit\u00e9 de certaines ressources, services et machines virtuelles, aboutissant \u00e0 l\u2019arr\u00eat des sites web de certains clients malchanceux.<\/p>\n\n\n\n<p><strong>II \u2013 Les technologies de refroidissement&nbsp;:<\/strong><\/p>\n\n\n\n<p>Comme nous l\u2019avons vu, la g\u00e9ographie influence grandement la technologie que l\u2019entreprise peut adopter. Ainsi, par souci d\u2019\u00e9conomie, certaines entreprises peuvent d\u00e9cider d\u2019utiliser des technologies moins performantes sur le plan \u00e9nerg\u00e9tique, avec de potentielles retomb\u00e9es sur la sant\u00e9 des habitants.<\/p>\n\n\n\n<p>Un proc\u00e9d\u00e9 semble cependant rem\u00e9dier aux probl\u00e8mes de consommations \u00e9lev\u00e9es en \u00e9lectricit\u00e9 et en eau ainsi que sur l\u2019impact \u00e9cologique&nbsp;: le syst\u00e8me adiabatique. Cette m\u00e9thode consiste \u00e0 recourir \u00e0 l\u2019\u00e9vaporation d\u2019une eau pr\u00e9alablement purifi\u00e9e pour faire baisser la temp\u00e9rature \u00e0 l\u2019int\u00e9rieur de la pi\u00e8ce o\u00f9 s\u2019activent les serveurs.<\/p>\n\n\n\n<p>La technologie adiabatique est l\u2019une des solutions de refroidissement les plus efficaces, qui peut \u00eatre facilement g\u00e9n\u00e9ralis\u00e9e. Elle est notamment utilis\u00e9e par Scaleway, le num\u00e9ro 2 fran\u00e7ais du <em>cloud<\/em>. Depuis 2017, l\u2019entreprise assure alimenter ses data centers \u00e0 partir d\u2019\u00e9nergie 100% renouvelable.<\/p>\n\n\n\n<p>Alors qu\u2019en France le <em>Water use efficiency<\/em> (l\u2019utilisation efficace de l\u2019eau) est en moyenne de 1,8 litres pour 1kWh pour un data center classique, Scaleway indique un taux inf\u00e9rieur \u00e0 0,15 litre. Arnaud de Bermingham, fondateur de Scaleway, partage dans un <em>tweet<\/em> que le syst\u00e8me de refroidissement du data center DC5 a r\u00e9ussi \u00e0 r\u00e9duire la temp\u00e9rature de 9 degr\u00e9s en utilisant seulement 3 grammes d\u2019eau. Ainsi, le centre DC5, l\u2019un des plus grands de France et en service depuis 2018, atteste aujourd\u2019hui d\u2019une empreinte environnementale parmi les plus basses d\u2019Europe.&nbsp;<\/p>\n\n\n\n<p>Pr\u00e8s de 40% d\u2019\u00e9nergie est \u00e9conomis\u00e9e par les data centers qui ont recours \u00e0 cette m\u00e9thode, en comparaison avec ceux utilisant un syst\u00e8me de climatisation.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"728\" src=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png\" alt=\"\" class=\"wp-image-3069\" srcset=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png 984w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620-300x222.png 300w, https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620-768x568.png 768w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><\/figure>\n\n\n\n<p><strong>III \u2013 L\u2019\u00e2ge des data centers et compensation de la consommation&nbsp;:<\/strong><\/p>\n\n\n\n<p>Par ailleurs, les site accueillant les centres de donn\u00e9es sont con\u00e7us pour des p\u00e9riodes de 20 \u00e0 25 ans. De fait, si un site construit il y a 5 ans n\u2019a pas \u00e9t\u00e9 con\u00e7u pour \u00e9conomiser l\u2019eau, il est impensable de le mettre hors ligne pendant une dur\u00e9e prolong\u00e9e afin d\u2019am\u00e9liorer le syst\u00e8me de refroidissement. La seule solution pour ces derniers est alors d\u2019avoir recours \u00e0 une utilisation plus raisonn\u00e9e de la ressource hydrique&nbsp;: recyclage de l\u2019eau, recours \u00e0 une eau non potable\u2026<\/p>\n\n\n\n<p>Ailleurs dans le monde, Google a d\u00e9velopp\u00e9 diff\u00e9rentes techniques pour compenser sa consommation d\u2019eau&nbsp;: collecteurs de pluie \u00e0 Dublin, \u00e9limination de plantes tr\u00e8s consommatrices d\u2019eau dans les montagnes de&nbsp; San Gabriel\u2026 Des syst\u00e8mes d\u2019irrigation de gouttes \u00e0 gouttes ajust\u00e9e aux conditions climatiques sont \u00e9galement d\u00e9velopp\u00e9s pour rendre les \u00e9cosyst\u00e8mes plus r\u00e9silients face au stress hydrique. L\u2019entreprise souhaite ainsi r\u00e9approvisionner 120% de sa consommation d\u2019eau. Cette question de l\u2019utilisation de l\u2019eau est capitale pour le g\u00e9ant Google qui a consomm\u00e9 plus de 12 milliards de litres d\u2019eau rien qu\u2019en 2019.<\/p>\n\n\n\n<p>Les data centers, plus qu\u2019un potentiel \u00e9conomique, sont essentiels pour le fonctionnement de notre \u00e9conomie digitalis\u00e9e. Alors que stocker nos donn\u00e9es rel\u00e8vent de l\u2019indispensable, les op\u00e9rateurs ont les cartes en main pour devenir plus vertueux sur long terme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019expansion fr\u00e9n\u00e9tique des data centers et la r\u00e9alit\u00e9 frappante du r\u00e9chauffement climatique obligent les industriels \u00e0 repenser leur strat\u00e9gie de refroidissement. Les data centers concentrent aujourd\u2019hui 1% de la consommation globale d\u2019\u00e9lectricit\u00e9 et pourraient repr\u00e9senter 3% de cette consommation en 2030. Ils sont \u00e9galement responsables de 0,3% des \u00e9missions de dioxyde de carbone. L\u2019\u00e9lectricit\u00e9 utilis\u00e9e [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55],"tags":[],"class_list":["post-3300","post","type-post","status-publish","format-standard","hentry","category-articles-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conflit autour de l&#039;usage de l&#039;eau - E&amp;HA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conflit autour de l&#039;usage de l&#039;eau - E&amp;HA\" \/>\n<meta property=\"og:description\" content=\"L\u2019expansion fr\u00e9n\u00e9tique des data centers et la r\u00e9alit\u00e9 frappante du r\u00e9chauffement climatique obligent les industriels \u00e0 repenser leur strat\u00e9gie de refroidissement. Les data centers concentrent aujourd\u2019hui 1% de la consommation globale d\u2019\u00e9lectricit\u00e9 et pourraient repr\u00e9senter 3% de cette consommation en 2030. Ils sont \u00e9galement responsables de 0,3% des \u00e9missions de dioxyde de carbone. L\u2019\u00e9lectricit\u00e9 utilis\u00e9e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/\" \/>\n<meta property=\"og:site_name\" content=\"E&amp;HA\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T12:40:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T09:35:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png\" \/>\n<meta name=\"author\" content=\"Eliott_Markus_Dev\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Eliott_Markus_Dev\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/\"},\"author\":{\"name\":\"Eliott_Markus_Dev\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/1a8d24fdf97320746d4eefc9c371cb25\"},\"headline\":\"Conflit autour de l&#8217;usage de l&#8217;eau\",\"datePublished\":\"2022-09-30T12:40:44+00:00\",\"dateModified\":\"2024-09-18T09:35:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/\"},\"wordCount\":1346,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/capture-decran-2022-09-30-a-143620.png\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/\",\"name\":\"Conflit autour de l'usage de l'eau - E&amp;HA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/capture-decran-2022-09-30-a-143620.png\",\"datePublished\":\"2022-09-30T12:40:44+00:00\",\"dateModified\":\"2024-09-18T09:35:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/1a8d24fdf97320746d4eefc9c371cb25\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/capture-decran-2022-09-30-a-143620.png\",\"contentUrl\":\"https:\\\/\\\/www.eha-consulting.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/capture-decran-2022-09-30-a-143620.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/conflit-autour-de-lusage-de-leau\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conflit autour de l&rsquo;usage de l&rsquo;eau\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/\",\"name\":\"E&amp;HA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eha-consulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/1a8d24fdf97320746d4eefc9c371cb25\",\"name\":\"Eliott_Markus_Dev\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g\",\"caption\":\"Eliott_Markus_Dev\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conflit autour de l'usage de l'eau - E&amp;HA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/","og_locale":"en_US","og_type":"article","og_title":"Conflit autour de l'usage de l'eau - E&amp;HA","og_description":"L\u2019expansion fr\u00e9n\u00e9tique des data centers et la r\u00e9alit\u00e9 frappante du r\u00e9chauffement climatique obligent les industriels \u00e0 repenser leur strat\u00e9gie de refroidissement. Les data centers concentrent aujourd\u2019hui 1% de la consommation globale d\u2019\u00e9lectricit\u00e9 et pourraient repr\u00e9senter 3% de cette consommation en 2030. Ils sont \u00e9galement responsables de 0,3% des \u00e9missions de dioxyde de carbone. L\u2019\u00e9lectricit\u00e9 utilis\u00e9e [&hellip;]","og_url":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/","og_site_name":"E&amp;HA","article_published_time":"2022-09-30T12:40:44+00:00","article_modified_time":"2024-09-18T09:35:37+00:00","og_image":[{"url":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png","type":"","width":"","height":""}],"author":"Eliott_Markus_Dev","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Eliott_Markus_Dev","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#article","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/"},"author":{"name":"Eliott_Markus_Dev","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/1a8d24fdf97320746d4eefc9c371cb25"},"headline":"Conflit autour de l&#8217;usage de l&#8217;eau","datePublished":"2022-09-30T12:40:44+00:00","dateModified":"2024-09-18T09:35:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/"},"wordCount":1346,"commentCount":0,"image":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png","articleSection":["Articles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/","url":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/","name":"Conflit autour de l'usage de l'eau - E&amp;HA","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#primaryimage"},"image":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png","datePublished":"2022-09-30T12:40:44+00:00","dateModified":"2024-09-18T09:35:37+00:00","author":{"@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/1a8d24fdf97320746d4eefc9c371cb25"},"breadcrumb":{"@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#primaryimage","url":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png","contentUrl":"https:\/\/www.eha-consulting.com\/wp-content\/uploads\/2022\/09\/capture-decran-2022-09-30-a-143620.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eha-consulting.com\/en\/conflit-autour-de-lusage-de-leau\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eha-consulting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Conflit autour de l&rsquo;usage de l&rsquo;eau"}]},{"@type":"WebSite","@id":"https:\/\/www.eha-consulting.com\/#website","url":"https:\/\/www.eha-consulting.com\/","name":"E&amp;HA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eha-consulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/1a8d24fdf97320746d4eefc9c371cb25","name":"Eliott_Markus_Dev","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e82a1c875af1d10692c1bb24d4aa42c9c59dd307bec1ee5f88b9145de9873f1b?s=96&d=mm&r=g","caption":"Eliott_Markus_Dev"}}]}},"_links":{"self":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=3300"}],"version-history":[{"count":1,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/3300\/revisions"}],"predecessor-version":[{"id":3301,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/3300\/revisions\/3301"}],"wp:attachment":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=3300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=3300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=3300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}