{"id":1433,"date":"2022-07-29T09:21:53","date_gmt":"2022-07-29T09:21:53","guid":{"rendered":"https:\/\/eha-wp.eliott-markus.digital\/?p=1433"},"modified":"2022-07-29T09:21:55","modified_gmt":"2022-07-29T09:21:55","slug":"gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque","status":"publish","type":"post","link":"https:\/\/www.eha-consulting.com\/en\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/","title":{"rendered":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1017\" srcset=\"https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg 1024w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-150x150.jpg 150w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-300x298.jpg 300w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-768x763.jpg 768w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-700x696.jpg 700w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1100x1093.jpg 1100w, https:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1.jpg 1564w\" src=\"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg\" alt=\"\"><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>Depuis plus d\u2019une d\u00e9cennie, nous confions nos donn\u00e9es au web, nous nous exposons, en tant qu\u2019individu, entreprise, grande organisation. Dans un monde o\u00f9 tout commence \u00e0 devenir immat\u00e9riel, les paiements, les flux d\u2019informations, tout peut potentiellement \u00eatre attaquable : du portefeuille, \u00e0 l\u2019image m\u00eame. Et les droits interne et international ont bien des difficult\u00e9s \u00e0 faire face aux probl\u00e8mes que pose le num\u00e9rique. Il n\u2019a pas de fronti\u00e8re, toute pr\u00e9sence se r\u00e9v\u00e8le donc un risque potentiel. La menace peut autant provenir de l\u2019int\u00e9rieur que de l\u2019ext\u00e9rieur, les salari\u00e9s n\u2019\u00e9tant bien souvent pas assez form\u00e9s \u00e0 l\u2019exploitation des outils permettant de contrer les risques informatiques, et aux r\u00e8gles \u00e9l\u00e9mentaires de s\u00e9curit\u00e9 informatique ; la culture d\u2019entreprise n\u2019est pas assez forte sur ces aspects.<\/p>\n\n\n\n<p><strong>Pourquoi devriez-vous porter une attention particuli\u00e8re \u00e0 la Cybers\u00e9curit\u00e9 : \u00ab une attention et un engagement de tous les instants. \u00bb [FireEye]<\/strong><\/p>\n\n\n\n<p>Ce que nous observons tout d\u2019abord, c\u2019est le manque de culture de la cybers\u00e9curit\u00e9 dans notre soci\u00e9t\u00e9, m\u00eame si on lui accorde de plus en plus d\u2019importance, \u00ab le d\u00e9ni du risque \u00bb dans les entreprises est encore bien pr\u00e9sent pour Frans Imbert-Vier, PDG de l\u2019agence Ubcom.<\/p>\n\n\n\n<p>En premier lieu, cela n\u2019arrive qu\u2019aux autres ; en second lieu qu\u2019une attaque fasse la une de la presse n\u2019arrive que quelques fois dans une ann\u00e9e.<\/p>\n\n\n\n<p>Pourtant, chaque jour, des entreprises sont victimes de la cybercriminalit\u00e9. En r\u00e9alit\u00e9, il est facile pour des groupes exp\u00e9riment\u00e9s de pirates informatiques sp\u00e9cialis\u00e9s dans le ransomware notamment \u2013 \u00ab structur\u00e9s comme des mafias \u00bb pour reprendre les mots de M. Imbert-Vier \u2013, ou pour de simples individus ayant des connaissances sur les malwares ou encore le phishing, d\u2019organiser une attaque avec peu de moyens. Il est donc d\u2019une importance vitale pour les entreprises de se pr\u00e9munir contre ce fl\u00e9au et de penser aux strat\u00e9gies de communication \u00e0 adopter en cas d\u2019attaque.<\/p>\n\n\n\n<p><strong>Les cons\u00e9quences d\u2019une cyberattaque : plusieurs cas embl\u00e9matiques<\/strong><\/p>\n\n\n\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Le cas de Target \u00ab Data breach \u00bb<\/strong><\/p>\n\n\n\n<p>Nous pouvons pour un premier exemple remonter jusqu\u2019en 2013 avec une attaque survenue en pleine p\u00e9riode de f\u00eates de fin d\u2019ann\u00e9e, et une r\u00e9action d\u2019entreprise tristement reconnue aujourd\u2019hui comme \u00e9tant un \u00ab cas d\u2019\u00e9cole \u00bb.<\/p>\n\n\n\n<p>Entre le 15 novembre et le 17 d\u00e9cembre, l\u2019enseigne de grande distribution am\u00e9ricaine Target est victime d\u2019une attaque d\u2019ampleur. Une br\u00e8che dans le syst\u00e8me de s\u00e9curit\u00e9 a permis aux pirates de voler plus de 40 millions de donn\u00e9es bancaires et 70 millions de donn\u00e9es personnelles. Pour donner une id\u00e9e de grandeur plus parlante, un tiers des Am\u00e9ricains a \u00e9t\u00e9 touch\u00e9 par cette attaque, pendant les f\u00eates. D\u00e9but 2014, suite aux investigations de l\u2019agence Reuters, on apprend que VISA Inc avait mis en garde les grandes enseignes contre les nouvelles strat\u00e9gies des hackers. VISA Inc avait m\u00eame donn\u00e9 les moyens \u00e0 celles-ci pour s\u2019en pr\u00e9munir. Reuters nous a \u00e9galement appris, que ce n\u2019est autre qu\u2019un blogueur, Brian Krebs \u2013 sp\u00e9cialiste en cybers\u00e9curit\u00e9 \u2013, qui a signal\u00e9 la br\u00e8che suite \u00e0 une probable fuite en interne. La r\u00e9action des investisseurs, puis du grand public a mis l\u2019enseigne au pied du mur, la for\u00e7ant \u00e0 r\u00e9v\u00e9ler l\u2019ampleur de l\u2019attaque. Plusieurs mois apr\u00e8s l\u2019attaque, un&nbsp;<a href=\"https:\/\/corporate.target.com\/press\/releases\/2014\/05\/statement-from-targets-board-of-directors\">communiqu\u00e9<\/a>&nbsp;de Target annonce un changement de gouvernance. Par ailleurs, l\u2019entreprise se dit confiante, exprime sa volont\u00e9 d\u2019entreprendre de v\u00e9ritables \u00ab transformations \u00bb pour l\u2019avenir et rappelle ces ambitions.<\/p>\n\n\n\n<p>La communication tardive a provoqu\u00e9 une r\u00e9action en cha\u00eene d\u00e9pr\u00e9ciant l\u2019entreprise, d\u00e9sormais connue pour \u00eatre \u00ab laxiste \u00bb en mati\u00e8re de s\u00e9curit\u00e9.&nbsp; Par ailleurs, le cas de Target illustre parfaitement l\u2019enchainement des sc\u00e9narios d\u2019\u00e9volution d\u00e9favorables apr\u00e8s une attaque. Voici pourquoi :<\/p>\n\n\n\n<p>En premier lieu, l\u2019attaque gr\u00e8ve le budget de l\u2019enseigne, qui doit \u00e0 grands frais se doter des meilleurs experts techniques pour colmater la faille. Elle doit \u00e9galement financer les frais de notification, les amendes, et le proc\u00e8s. Pratiquement dans le m\u00eame temps, les m\u00e9dias s\u2019emparent de cette information et alarment la client\u00e8le ; l\u2019enseigne est discr\u00e9dit\u00e9e.<\/p>\n\n\n\n<p>L\u2019\u00e9v\u00e9nement entra\u00eene la d\u00e9mission du CEO Gregg Steinhafel, quelques mois apr\u00e8s l\u2019attaque. Il est accus\u00e9 de n\u2019avoir pas r\u00e9agi suffisamment rapidement apr\u00e8s la d\u00e9couverte du piratage, et n\u2019avoir pas pris les mesures appropri\u00e9es et jug\u00e9es n\u00e9cessaires. Il rejettera ses accusations.<\/p>\n\n\n\n<p><em>\u00ab Depuis le d\u00e9but de cette histoire de vol massif de donn\u00e9es, je me suis engag\u00e9 \u00e0 ce que Target se transforme en une meilleure compagnie tourn\u00e9e plus que jamais dans la satisfaction client. \u00bb<\/em><\/p>\n\n\n\n<p>Lettre adress\u00e9e au conseil d\u2019administration de Target.<\/p>\n\n\n\n<p>Les concurrents se sont servis de l\u2019emballement m\u00e9diatique pour r\u00e9cup\u00e9rer ses clients. En outre, le bilan humain et financier de cette attaque se r\u00e9v\u00e8le tr\u00e8s lourd pour Target, son image est durablement entach\u00e9e, en t\u00e9moignent encore aujourd\u2019hui les nombreux tweets sur cette affaire.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/tweet-data-breach.png\" alt=\"\" class=\"wp-image-23656\"\/><\/figure><\/div>\n\n\n\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Le cas TalkTalk<\/strong><\/p>\n\n\n\n<p>Deux ans apr\u00e8s le \u00ab Data Breach \u00bb, une autre cyberattaque d\u2019ampleur touche l\u2019op\u00e9rateur de t\u00e9l\u00e9phonie mobile britannique TalkTalk. Il admet alors (pour la troisi\u00e8me fois) qu\u2019il vient d\u2019\u00eatre victime d\u2019un vol de donn\u00e9es. Selon ses services, 150 000 de ses abonn\u00e9s auraient \u00e9t\u00e9 touch\u00e9s. Si l\u2019incident n\u2019est pas consid\u00e9r\u00e9 comme \u00ab une vaste attaque \u00bb, les cons\u00e9quences seront tout aussi lourdes. Pourquoi ? Les pirates informatiques ayant commis ce vol sont\u2026 des adolescents. Toute communication sur l\u2019intrusion est vaine, le simple profil des hackers a inflig\u00e9 \u00e0 l\u2019op\u00e9rateur une lourde perte en cr\u00e9dibilit\u00e9.<\/p>\n\n\n\n<p><strong>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Le cas d\u2019Altran<\/strong><\/p>\n\n\n\n<p>Mi-janvier 2019, l\u2019entreprise de conseil en ing\u00e9nierie proc\u00e8de \u00e0 la d\u00e9connexion de tous ses serveurs suite \u00e0 une attaque. Il est int\u00e9ressant d\u2019observer son temps de r\u00e9action. Il lui a fallu quatre jours pour admettre officiellement l\u2019incident. Le 28 janvier, l\u2019entreprise diffuse finalement un communiqu\u00e9, qui reste laconique :<\/p>\n\n\n\n<p>\u00ab Nous avons mobilis\u00e9 des experts techniques et d\u2019investigation ind\u00e9pendants mondialement reconnus, et l\u2019enqu\u00eate que nous avons men\u00e9e avec eux n\u2019a r\u00e9v\u00e9l\u00e9 aucun vol de donn\u00e9es ni aucun cas de propagation de l\u2019incident \u00e0 nos clients. Notre plan de r\u00e9tablissement se d\u00e9roule comme pr\u00e9vu et nos \u00e9quipes techniques sont pleinement mobilis\u00e9es \u00bb.<\/p>\n\n\n\n<p>Il peut \u00eatre qualifi\u00e9 de classique, de laconique, mais il t\u00e9moigne surtout d\u2019un d\u00e9ni de la part de l\u2019entreprise. Il \u00e9voque seulement l\u2019intervention \u00ab d\u2019experts \u00bb, alors que finalement, une dizaine de jours apr\u00e8s l\u2019attaque, la soci\u00e9t\u00e9 tournera toujours au ralenti, ce qui bien entendu, inqui\u00e9tera ses clients au nombre desquels Safran, la SNCF, et bien d\u2019autres. Avec une communication opaque, les clients peuvent ainsi s\u2019imaginer que l\u2019attaque est bien plus importante que celle dont ils ont connaissance.<\/p>\n\n\n\n<p><strong>Que retenir de ces r\u00e9actions et de la communication des entreprises apr\u00e8s ces attaques ?<\/strong><\/p>\n\n\n\n<p>Tous les domaines d\u2019activit\u00e9 peuvent \u00eatre touch\u00e9s, et bien \u00e9videmment, selon le profil des pirates, l\u2019entreprise vis\u00e9e, l\u2019ampleur de l\u2019attaque, la cible pr\u00e9cise, voici quelques erreurs notables que nous pouvons relever dans les communiqu\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Absence de communication spontan\u00e9e :<\/strong>&nbsp;l\u2019entreprise s\u2019exprime parce qu\u2019elle y est contrainte. G\u00e9n\u00e9ralement, la fuite, ou m\u00eame l\u2019attaque,&nbsp; provient de l\u2019interne (des employ\u00e9s qui en parlent \u00e0 leurs amis, etc.), ou de blogueurs experts dans le domaine, entachant encore plus l\u2019image de l\u2019entreprise qui a donc voulu au d\u00e9part, taire l\u2019affaire. Les blogueurs sp\u00e9cialis\u00e9s dans le cyber sont \u00e0 suivre avec attention, ils sont reconnus, peuvent avoir les informations les premiers et sont parfois m\u00eame en contact direct avec les pirates. Dans le paysage cyber fran\u00e7ais, on pourrait parler de Zataz.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Emploi de mots susceptibles de minimiser l\u2019importance de l\u2019\u00e9v\u00e9nement pour le client<\/strong>&nbsp;(dans l\u2019hypoth\u00e8se o\u00f9 l\u2019entreprise communique) ; ainsi, on note souvent la r\u00e9p\u00e9tition de vocables tels que \u00ab aucun \u00bb, \u00ab simple incident \u00bb, \u00ab n\u2019a pas \u00bb, comme si une attaque \u00e9tait n\u00e9gligeable. Dans le cas de Ramsay G\u00e9n\u00e9rale de sant\u00e9 : \u00ab L\u2019attaque handicape le travail mais n\u2019a pas d\u2019impact sur les patients \u00bb. Pourtant, si le travail des employ\u00e9s est perturb\u00e9, les patients peuvent \u00eatre impact\u00e9s d\u2019une certaine mani\u00e8re, ou l\u00e9gitimement inquiets\u2026<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>G\u00e9n\u00e9ralement, quelques \u00e9l\u00e9ments chronologiques sont fournis,<\/strong>&nbsp;mais le manque de transparence, une communication prosa\u00efque, sont manifestes ; et des questions demeurent, la dur\u00e9e de l\u2019intrusion par exemple, le volume de donn\u00e9es subtilis\u00e9es, mais aussi le flou quant au r\u00e9tablissement des services.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Facteur humain souvent sous-estim\u00e9.<\/strong>&nbsp;Les internautes aujourd\u2019hui connaissent le risque majeur que pr\u00e9sente le num\u00e9rique. Il faut donc plus de r\u00e9silience, plus de transparence. Une cyberattaque induit de multiples rebondissements d\u00e9l\u00e9t\u00e8res : des d\u00e9missions, un m\u00e9contentement ressenti par plusieurs parties prenantes, des pertes de ressources humaines et financi\u00e8res.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Il est enfin fondamental de penser \u00e0 l\u2019interne<\/strong>. Vos employ\u00e9s sont inquiets, ils n\u2019ont plus acc\u00e8s \u00e0 leurs outils, ne savent peut-\u00eatre pas s\u2019ils vont \u00eatre pay\u00e9s, s\u2019ils vont devoir poser leurs cong\u00e9s etc. suivant l\u2019ampleur de l\u2019attaque.<\/li><\/ul>\n\n\n\n<p><strong>Mais alors, quelles strat\u00e9gies adopter ?<\/strong><\/p>\n\n\n\n<p>La strat\u00e9gie \u00e0 adopter est bien entendu diff\u00e9rente selon les cas, mais que ce soit une atteinte \u00e0 la r\u00e9putation, une perte de confiance des clients, de ses employ\u00e9s etc. voici quelques recommandations \u00e0 prendre en compte :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Ne pas se laisser aller au d\u00e9ni :<\/strong><\/li><\/ul>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La crise va durer longtemps<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Une gestion de crise op\u00e9rationnelle ou technique, qui n\u2019implique que l\u2019IT n\u2019est pas suffisante (r\u00e9tablir les serveurs, r\u00e9cup\u00e9rer les donn\u00e9es, etc., constitue bien sur l\u2019urgence, mais cela ne suffit pas)<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Les attaques cyber occasionnent des crises multiformes (r\u00e9putation, juridique (loi RGPD), RH, scandale de type compliance, etc.)<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Prendre l\u2019initiative de diffuser un communiqu\u00e9 rapidement&nbsp;:<\/strong><\/li><\/ul>\n\n\n\n<p>si possible avant que des internautes, blogueurs ou journaux relayent l\u2019information. Ce dernier doit \u00eatre clair, r\u00e9sumant la situation avec le plus de transparence possible. Ne pas laisser le vide et la parole aux nombreux articles, aux interrogations, aux r\u00e9actions.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Des updates sont toujours appr\u00e9ciables&nbsp;:<\/strong><\/li><\/ul>\n\n\n\n<p>elles d\u00e9montrent la volont\u00e9 de l\u2019entreprise de tenir au courant ses clients, ses actionnaires, des \u00e9volutions de la situation jusqu\u2019au retour \u00e0 la normale des syst\u00e8mes, et de l\u2019activit\u00e9. Cette man\u0153uvre permettra de maintenir un relationnel avec les diff\u00e9rents acteurs, pour \u00ab occuper le terrain \u00bb, et peut contribuer \u00e0 entretenir la confiance qu\u2019ils accordent \u00e0 votre structure.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Cartographier ses parties prenantes et anticiper les risques potentiels !<\/strong><\/li><\/ul>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>En interne&nbsp;<\/strong>: penser que les employ\u00e9s se posent peut-\u00eatre des questions sur les donn\u00e9es vol\u00e9es (mes donn\u00e9es personnelles sont-elles sauves ?). Penser \u00e9galement \u00e0 les rassurer sur la question de la p\u00e9rennit\u00e9 de l\u2019entreprise et de leur place au sein de cette structure. Penser \u00e0 l\u2019anxi\u00e9t\u00e9 que peut provoquer la perte des outils de travail (agenda, boites mails, etc.).<\/p>\n\n\n\n<p>Ici, le cas de Saint-Gobain est int\u00e9ressant. En juin 2017, la structure a subi une attaque par le groupe NotPeyta depuis une filiale en Ukraine. Des milliers de donn\u00e9es ont \u00e9t\u00e9 crypt\u00e9es, les r\u00e9seaux ont d\u00fb \u00eatre suspendus, entra\u00eenant une perte de chiffre d\u2019affaires de 220 millions d\u2019euros. L\u2019attitude du groupe en interne pour g\u00e9rer cette crise doit \u00eatre regard\u00e9e de plus pr\u00e8s. Le pr\u00e9sident s\u2019est notamment attel\u00e9 \u00e0 rassurer ses collaborateurs et s\u2019est montr\u00e9 tr\u00e8s pr\u00e9sent, en communiquant r\u00e9guli\u00e8rement sur la situation et sur la reprise de l\u2019activit\u00e9. Cet engagement a suscit\u00e9 un v\u00e9ritable team building, un engagement de la part des collaborateurs qui n\u2019\u00e9taient pas habitu\u00e9 \u00e0 cette communication. C\u2019\u00e9tait \u00e9galement un moyen d\u2019encadrer les informations \u2013 certifi\u00e9es ou non \u2013 que pouvaient \u00e9mettre les nombreuses parties prenantes internes. \u00ab \u00ab&nbsp; je compte sur vous, il faut servir nos clients, je vous tiens au courant, faire attention \u00e0 ne pas propager des rumeurs, etc, ne pas poster les \u00e9crans noirs. \u00bb<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>&nbsp;L\u2019objectif :<\/strong>&nbsp;\u00e9viter les RPS, la fuite de talents, la d\u00e9motivation, la perte de productivit\u00e9\u2026<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>&nbsp; En externe :<\/strong>&nbsp;penser aux clients, aux fournisseurs, aux sous-traitants et prestataires. Penser \u00e0 leurs inqui\u00e9tudes (ai-je \u00e9t\u00e9 contamin\u00e9 par le virus ? mes donn\u00e9es ont-elles \u00e9t\u00e9 vol\u00e9es ? comment vais-je \u00eatre pay\u00e9 ? etc.)<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<strong>&nbsp; L\u2019objectif :&nbsp;<\/strong>ne pas s\u2019ali\u00e9ner de parties prenantes, ne pas perdre de clients ou de contrats, travailler sa social&nbsp;<em>license to opperate<\/em>.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Ne pas sous-estimer le facteur humain dans une crise :<\/strong><\/li><\/ul>\n\n\n\n<p>remercier ses employ\u00e9s qui \u0153uvrent pour le r\u00e9tablissement de la situation et qui doivent g\u00e9rer une situation anxiog\u00e8ne : faire face \u00e0 une potentielle perte de confiance de la client\u00e8le peut s\u2019av\u00e9rer compliqu\u00e9. De m\u00eame, il est tr\u00e8s important de faire preuve d\u2019empathie envers des clients qui se retrouvent l\u00e9s\u00e9s, notamment en cas de vol de donn\u00e9es ; il faut rassurer, voire parfois pr\u00e9senter des excuses.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Penser aux canaux de communication disponibles :<\/strong><\/li><\/ul>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; l\u2019intranet est-il vraiment consult\u00e9 ? vos bases de donn\u00e9es sont-elles \u00e0 jour ?<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les interlocuteurs habituels (RH, commerciaux, etc.) ont-ils \u00e9t\u00e9 brief\u00e9s pour aligner la communication ? ont-ils les ressources n\u00e9cessaires pour faire face \u00e0 l\u2019afflux de questions ?<\/p>\n\n\n\n<p>o&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; les employ\u00e9s peuvent-ils \u00eatre les ambassadeurs de l\u2019entreprise ? si oui, leur avez-vous fourni assez d\u2019\u00e9l\u00e9ments ?<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>User de certains vocables avec prudence :<\/strong><\/li><\/ul>\n\n\n\n<p>Une all\u00e9gation telle que : \u00ab L\u2019enqu\u00eate est en cours et d\u00e9montrera etc. \u00bb peut s\u2019av\u00e9rer g\u00eanante par la suite. Il arrive que l\u2019enqu\u00eate d\u00e9montre justement que le groupe concern\u00e9 par l\u2019attaque ne prenait pas les mesures ad\u00e9quates pour la protection de ses syst\u00e8mes d\u2019information.&nbsp; Le mieux reste d\u2019accompagner le texte d\u2019une description des mesures prises avant pendant et apr\u00e8s la crise. Si enfin vous pouvez vous livrer \u00e0 la plus grande transparence, n\u2019h\u00e9sitez pas \u00e0 communiquer ce que vous savez.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Penser au retour d\u2019exp\u00e9rience :<\/strong><\/li><\/ul>\n\n\n\n<p>Dans le cas de Saint Gobain, l\u2019entreprise n\u2019a pas h\u00e9sit\u00e9 \u00e0 revenir plusieurs fois sur cette attaque afin de montrer au grand public, aux clients, qu\u2019elle en \u00e9tait sortie plus forte. Elle a notamment renforc\u00e9 sa politique cyber d\u00e9fense pour r\u00e9agir plus rapidement, d\u00e9tecter les failles en amont et identifier les risques, dans la plus grande r\u00e9silience. Par ailleurs, elle organise r\u00e9guli\u00e8rement des tests pour sensibiliser l\u2019ensemble des collaborateurs aux actes de cyber malveillance. Le directeur op\u00e9rationnel du groupe, Claude Imauven, avait d\u2019ailleurs d\u00e9clar\u00e9&nbsp;&nbsp;<em>\u00ab L\u2019attaque du mois de juin nous a permis d\u2019avoir une vision de ce que cela peut nous co\u00fbter au maximum\u2026 \u00bb<\/em>&nbsp;. D\u2019o\u00f9 l\u2019importance de se pr\u00e9parer \u00e0 toutes les \u00e9ventualit\u00e9s aujourd\u2019hui et de revenir sur cette exp\u00e9rience.<\/p>\n\n\n\n<p>De m\u00eame, le cas d\u2019Airbus est notable. Fin janvier 2019, la compagnie a \u00e9t\u00e9 victime d\u2019une cyberattaque massive. Le communiqu\u00e9 de presse \u00e9tait exhaustif sur la description de l\u2019attaque, ce qui a \u00e9t\u00e9 vol\u00e9 et divulgu\u00e9. \u00ab Des donn\u00e9es \u00e0 caract\u00e8re personnel ont \u00e9t\u00e9 consult\u00e9es (\u2026) essentiellement des coordonn\u00e9es professionnelles et des identifiants informatiques d\u2019employ\u00e9s d\u2019Airbus en Europe \u00bb. Si ces d\u00e9clarations peuvent inqui\u00e9ter&nbsp; au premier abord, elles sont obligatoires, et peuvent donc aussi se r\u00e9v\u00e9ler un moyen pour l\u2019entreprise de d\u00e9montrer toute sa transparence envers ses collaborateurs et clients. Le communiqu\u00e9 se termine par des mentions qui se veulent rassurantes pour tout le monde : \u00ab Aucun impact sur les activit\u00e9s commerciales \u00bb. Et l\u2019\u00e9v\u00e8nement est qualifi\u00e9 \u00ab d\u2019incident \u00bb, on minimise donc son impact et on rappelle que ce n\u2019est qu\u2019un accident de parcours, ce qui ne devrait pas mettre en p\u00e9ril la confiance accord\u00e9e \u00e0 l\u2019entreprise.<\/p>\n\n\n\n<p><strong>Sources :<\/strong><\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.lemonde.fr\/emploi\/article\/2019\/12\/11\/le-turnover-des-salaries-penalise-la-securite-informatique_6022404_1698637.html#xtor=AL-32280270<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.faceaurisque.com\/2019\/01\/25\/cybersecurite-barometre-2019-linquietant-constat-du-cesin-sur-les-cyberattaques\/<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.fireeye.fr\/current-threats\/what-is-cyber-security.html<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.saint-gobain.com\/sites\/sgcom.master\/files\/03-07-2017_cp_va.pdf<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.ticsante.com\/story\/4735\/le-groupe-ramsay-generale-de-sante-victime-d-une-cyberattaque.html<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.eurofins.com\/mediacentre\/safeharborstatement\/?page=https:\/\/www.eurofins.com\/media-centre\/press-releases-2019\/2019-06-03-8\/<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; http:\/\/www.eclaireursdelacom.fr\/la-reputation-des-entreprises-menacee-par-les-cyberattaques\/<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.riskinsight-wavestone.com\/2014\/05\/target-6-mois-tard-quel-retour-cyber-assurance\/<\/p>\n\n\n\n<p>\u2022&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; https:\/\/www.usinenouvelle.com\/editorial\/chez-saint-gobain-il-y-un-avant-et-un-apres-la-cyber-attaque.N651134<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Depuis plus d\u2019une d\u00e9cennie, nous confions nos donn\u00e9es au web, nous nous exposons, en tant qu\u2019individu, entreprise, grande organisation. Dans un monde o\u00f9 tout commence \u00e0 devenir immat\u00e9riel, les paiements, les flux d\u2019informations, tout peut potentiellement \u00eatre attaquable : du portefeuille, \u00e0 l\u2019image m\u00eame. Et les droits interne et international ont bien des difficult\u00e9s \u00e0 [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1433","post","type-post","status-publish","format-standard","hentry","category-articles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA\" \/>\n<meta property=\"og:description\" content=\"Depuis plus d\u2019une d\u00e9cennie, nous confions nos donn\u00e9es au web, nous nous exposons, en tant qu\u2019individu, entreprise, grande organisation. Dans un monde o\u00f9 tout commence \u00e0 devenir immat\u00e9riel, les paiements, les flux d\u2019informations, tout peut potentiellement \u00eatre attaquable : du portefeuille, \u00e0 l\u2019image m\u00eame. Et les droits interne et international ont bien des difficult\u00e9s \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/\" \/>\n<meta property=\"og:site_name\" content=\"E&amp;HA\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-29T09:21:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-29T09:21:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg\" \/>\n<meta name=\"author\" content=\"Administration\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administration\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/\"},\"author\":{\"name\":\"Administration\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/f33b5112edd7919c121178061153ea90\"},\"headline\":\"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque\",\"datePublished\":\"2022-07-29T09:21:53+00:00\",\"dateModified\":\"2022-07-29T09:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/\"},\"wordCount\":3121,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gestiondecrise.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IMG_20200331_122808-1-1024x1017.jpg\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/\",\"name\":\"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/gestiondecrise.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IMG_20200331_122808-1-1024x1017.jpg\",\"datePublished\":\"2022-07-29T09:21:53+00:00\",\"dateModified\":\"2022-07-29T09:21:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/f33b5112edd7919c121178061153ea90\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#primaryimage\",\"url\":\"http:\\\/\\\/gestiondecrise.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IMG_20200331_122808-1-1024x1017.jpg\",\"contentUrl\":\"http:\\\/\\\/gestiondecrise.fr\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/IMG_20200331_122808-1-1024x1017.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eha-consulting.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#website\",\"url\":\"https:\\\/\\\/www.eha-consulting.com\\\/\",\"name\":\"E&amp;HA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eha-consulting.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eha-consulting.com\\\/#\\\/schema\\\/person\\\/f33b5112edd7919c121178061153ea90\",\"name\":\"Administration\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g\",\"caption\":\"Administration\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/","og_locale":"en_US","og_type":"article","og_title":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA","og_description":"Depuis plus d\u2019une d\u00e9cennie, nous confions nos donn\u00e9es au web, nous nous exposons, en tant qu\u2019individu, entreprise, grande organisation. Dans un monde o\u00f9 tout commence \u00e0 devenir immat\u00e9riel, les paiements, les flux d\u2019informations, tout peut potentiellement \u00eatre attaquable : du portefeuille, \u00e0 l\u2019image m\u00eame. Et les droits interne et international ont bien des difficult\u00e9s \u00e0 [&hellip;]","og_url":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/","og_site_name":"E&amp;HA","article_published_time":"2022-07-29T09:21:53+00:00","article_modified_time":"2022-07-29T09:21:55+00:00","og_image":[{"url":"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg","type":"","width":"","height":""}],"author":"Administration","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Administration","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#article","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/"},"author":{"name":"Administration","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/f33b5112edd7919c121178061153ea90"},"headline":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque","datePublished":"2022-07-29T09:21:53+00:00","dateModified":"2022-07-29T09:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/"},"wordCount":3121,"commentCount":0,"image":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#primaryimage"},"thumbnailUrl":"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg","articleSection":["Articles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/","url":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/","name":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque - E&amp;HA","isPartOf":{"@id":"https:\/\/www.eha-consulting.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#primaryimage"},"image":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#primaryimage"},"thumbnailUrl":"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg","datePublished":"2022-07-29T09:21:53+00:00","dateModified":"2022-07-29T09:21:55+00:00","author":{"@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/f33b5112edd7919c121178061153ea90"},"breadcrumb":{"@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#primaryimage","url":"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg","contentUrl":"http:\/\/gestiondecrise.fr\/wp-content\/uploads\/2020\/03\/IMG_20200331_122808-1-1024x1017.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eha-consulting.com\/gestion-de-crise-et-communication-sensible-en-cas-de-cyberattaque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eha-consulting.com\/en\/"},{"@type":"ListItem","position":2,"name":"Gestion de crise et communication sensible en cas de&nbsp;cyberattaque"}]},{"@type":"WebSite","@id":"https:\/\/www.eha-consulting.com\/#website","url":"https:\/\/www.eha-consulting.com\/","name":"E&amp;HA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eha-consulting.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.eha-consulting.com\/#\/schema\/person\/f33b5112edd7919c121178061153ea90","name":"Administration","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/335d85880c719894ba30b16df0eae6b00988dd4be6ecbd92b4fb646b51026eb0?s=96&d=mm&r=g","caption":"Administration"}}]}},"_links":{"self":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/1433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=1433"}],"version-history":[{"count":0,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/posts\/1433\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=1433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=1433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eha-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=1433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}